{"id":15354,"date":"2021-05-05T13:09:14","date_gmt":"2021-05-05T11:09:14","guid":{"rendered":"https:\/\/www.groupg4.com\/en\/?post_type=avada_portfolio&#038;p=15354"},"modified":"2021-07-28T11:43:26","modified_gmt":"2021-07-28T09:43:26","slug":"rimowa-flagship-hong-kong","status":"publish","type":"avada_portfolio","link":"https:\/\/www.groupg4.com\/en\/portfolio-items\/rimowa-flagship-hong-kong\/","title":{"rendered":"Rimowa flagship Hong Kong"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container hundred-percent-fullwidth non-hundred-percent-height-scrolling fusion-sticky-container\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" data-transition-offset=\"0\" data-scroll-offset=\"0\" data-sticky-small-visibility=\"1\" data-sticky-medium-visibility=\"1\" data-sticky-large-visibility=\"1\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"width:104% !important;max-width:104% !important;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_5_6 5_6 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:83.333333333333%;--awb-margin-top-large:0px;--awb-spacing-right-large:2.304%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:2.304%;--awb-width-medium:100%;--awb-order-medium:2;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:2;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"awb-gallery-wrapper awb-gallery-wrapper-1 button-span-no\"><div style=\"margin:-8px;--awb-bordersize:0px;\" class=\"fusion-gallery fusion-gallery-container fusion-grid-4 fusion-columns-total-6 fusion-gallery-layout-masonry fusion-gallery-1\"><div class=\"fusion-grid-column fusion-gallery-column fusion-gallery-column-4 hover-type-none fusion-grid-sizer\"><\/div><div style=\"padding:8px;\" class=\"fusion-grid-column fusion-gallery-column fusion-gallery-column-4 hover-type-none fusion-element-portrait\"><div class=\"fusion-gallery-image\"><div style=\"background-image:url(https:\/\/www.groupg4.com\/en\/wp-content\/uploads\/2021\/05\/RIMOWA-FLAGSHIP-HONG-KONG-G4GROUP-002.webp);padding-top:calc((100% + 16px) * 1.6);background-position:;\" class=\"fusion-masonry-element-container\"><img decoding=\"async\" src=\"https:\/\/www.groupg4.com\/en\/wp-content\/uploads\/2021\/05\/RIMOWA-FLAGSHIP-HONG-KONG-G4GROUP-002.webp\" width=\"800\" height=\"1200\" alt=\"\" title=\"RIMOWA-FLAGSHIP-HONG KONG-G4GROUP-002\" aria-label=\"RIMOWA-FLAGSHIP-HONG KONG-G4GROUP-002\" class=\"img-responsive wp-image-15355\" srcset=\"https:\/\/www.groupg4.com\/en\/wp-content\/uploads\/2021\/05\/RIMOWA-FLAGSHIP-HONG-KONG-G4GROUP-002-200x300.webp 200w, https:\/\/www.groupg4.com\/en\/wp-content\/uploads\/2021\/05\/RIMOWA-FLAGSHIP-HONG-KONG-G4GROUP-002-400x600.webp 400w, https:\/\/www.groupg4.com\/en\/wp-content\/uploads\/2021\/05\/RIMOWA-FLAGSHIP-HONG-KONG-G4GROUP-002-600x900.webp 600w, https:\/\/www.groupg4.com\/en\/wp-content\/uploads\/2021\/05\/RIMOWA-FLAGSHIP-HONG-KONG-G4GROUP-002.webp 800w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 1215px) 312px, (min-width: 1124px) 415px, (min-width: 1032px) 623px, (min-width: 940px) 1032px, \" \/><\/div><\/div><\/div><div style=\"padding:8px;\" class=\"fusion-grid-column fusion-gallery-column fusion-gallery-column-4 hover-type-none fusion-element-grid\"><div class=\"fusion-gallery-image\"><div style=\"background-image:url(https:\/\/www.groupg4.com\/en\/wp-content\/uploads\/2021\/05\/RIMOWA-FLAGSHIP-HONG-KONG-G4GROUP-003.webp);padding-top:calc((100% + 16px) * 0.8 - 8px);background-position:;\" class=\"fusion-masonry-element-container\"><img decoding=\"async\" src=\"https:\/\/www.groupg4.com\/en\/wp-content\/uploads\/2021\/05\/RIMOWA-FLAGSHIP-HONG-KONG-G4GROUP-003.webp\" width=\"1200\" height=\"800\" alt=\"\" title=\"RIMOWA-FLAGSHIP-HONG KONG-G4GROUP-003\" aria-label=\"RIMOWA-FLAGSHIP-HONG KONG-G4GROUP-003\" class=\"img-responsive wp-image-15356\" srcset=\"https:\/\/www.groupg4.com\/en\/wp-content\/uploads\/2021\/05\/RIMOWA-FLAGSHIP-HONG-KONG-G4GROUP-003-200x133.webp 200w, https:\/\/www.groupg4.com\/en\/wp-content\/uploads\/2021\/05\/RIMOWA-FLAGSHIP-HONG-KONG-G4GROUP-003-400x267.webp 400w, https:\/\/www.groupg4.com\/en\/wp-content\/uploads\/2021\/05\/RIMOWA-FLAGSHIP-HONG-KONG-G4GROUP-003-600x400.webp 600w, https:\/\/www.groupg4.com\/en\/wp-content\/uploads\/2021\/05\/RIMOWA-FLAGSHIP-HONG-KONG-G4GROUP-003-800x533.webp 800w, https:\/\/www.groupg4.com\/en\/wp-content\/uploads\/2021\/05\/RIMOWA-FLAGSHIP-HONG-KONG-G4GROUP-003.webp 1200w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 1215px) 312px, (min-width: 1124px) 415px, (min-width: 1032px) 623px, (min-width: 940px) 1032px, \" \/><\/div><\/div><\/div><div style=\"padding:8px;\" class=\"fusion-grid-column fusion-gallery-column fusion-gallery-column-4 hover-type-none fusion-element-grid\"><div class=\"fusion-gallery-image\"><div style=\"background-image:url(https:\/\/www.groupg4.com\/en\/wp-content\/uploads\/2021\/05\/RIMOWA-FLAGSHIP-HONG-KONG-G4GROUP-004.webp);padding-top:calc((100% + 16px) * 0.8 - 8px);background-position:;\" class=\"fusion-masonry-element-container\"><img decoding=\"async\" src=\"https:\/\/www.groupg4.com\/en\/wp-content\/uploads\/2021\/05\/RIMOWA-FLAGSHIP-HONG-KONG-G4GROUP-004.webp\" width=\"1200\" height=\"800\" alt=\"\" title=\"RIMOWA-FLAGSHIP-HONG KONG-G4GROUP-004\" aria-label=\"RIMOWA-FLAGSHIP-HONG KONG-G4GROUP-004\" class=\"img-responsive wp-image-15357\" srcset=\"https:\/\/www.groupg4.com\/en\/wp-content\/uploads\/2021\/05\/RIMOWA-FLAGSHIP-HONG-KONG-G4GROUP-004-200x133.webp 200w, https:\/\/www.groupg4.com\/en\/wp-content\/uploads\/2021\/05\/RIMOWA-FLAGSHIP-HONG-KONG-G4GROUP-004-400x267.webp 400w, https:\/\/www.groupg4.com\/en\/wp-content\/uploads\/2021\/05\/RIMOWA-FLAGSHIP-HONG-KONG-G4GROUP-004-600x400.webp 600w, https:\/\/www.groupg4.com\/en\/wp-content\/uploads\/2021\/05\/RIMOWA-FLAGSHIP-HONG-KONG-G4GROUP-004-800x533.webp 800w, https:\/\/www.groupg4.com\/en\/wp-content\/uploads\/2021\/05\/RIMOWA-FLAGSHIP-HONG-KONG-G4GROUP-004.webp 1200w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 1215px) 312px, (min-width: 1124px) 415px, (min-width: 1032px) 623px, (min-width: 940px) 1032px, \" \/><\/div><\/div><\/div><div style=\"padding:8px;\" class=\"fusion-grid-column fusion-gallery-column fusion-gallery-column-4 hover-type-none fusion-element-portrait\"><div class=\"fusion-gallery-image\"><div style=\"background-image:url(https:\/\/www.groupg4.com\/en\/wp-content\/uploads\/2021\/05\/RIMOWA-FLAGSHIP-HONG-KONG-G4GROUP-007.webp);padding-top:calc((100% + 16px) * 1.6);background-position:;\" class=\"fusion-masonry-element-container\"><img decoding=\"async\" src=\"https:\/\/www.groupg4.com\/en\/wp-content\/uploads\/2021\/05\/RIMOWA-FLAGSHIP-HONG-KONG-G4GROUP-007.webp\" width=\"800\" height=\"1200\" alt=\"\" title=\"RIMOWA-FLAGSHIP-HONG KONG-G4GROUP-007\" aria-label=\"RIMOWA-FLAGSHIP-HONG KONG-G4GROUP-007\" class=\"img-responsive wp-image-15360\" srcset=\"https:\/\/www.groupg4.com\/en\/wp-content\/uploads\/2021\/05\/RIMOWA-FLAGSHIP-HONG-KONG-G4GROUP-007-200x300.webp 200w, https:\/\/www.groupg4.com\/en\/wp-content\/uploads\/2021\/05\/RIMOWA-FLAGSHIP-HONG-KONG-G4GROUP-007-400x600.webp 400w, https:\/\/www.groupg4.com\/en\/wp-content\/uploads\/2021\/05\/RIMOWA-FLAGSHIP-HONG-KONG-G4GROUP-007-600x900.webp 600w, https:\/\/www.groupg4.com\/en\/wp-content\/uploads\/2021\/05\/RIMOWA-FLAGSHIP-HONG-KONG-G4GROUP-007.webp 800w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 1215px) 312px, (min-width: 1124px) 415px, (min-width: 1032px) 623px, (min-width: 940px) 1032px, \" \/><\/div><\/div><\/div><div style=\"padding:8px;\" class=\"fusion-grid-column fusion-gallery-column fusion-gallery-column-4 hover-type-none fusion-element-grid\"><div class=\"fusion-gallery-image\"><div style=\"background-image:url(https:\/\/www.groupg4.com\/en\/wp-content\/uploads\/2021\/05\/RIMOWA-FLAGSHIP-HONG-KONG-G4GROUP-005.webp);padding-top:calc((100% + 16px) * 0.8 - 8px);background-position:;\" class=\"fusion-masonry-element-container\"><img decoding=\"async\" src=\"https:\/\/www.groupg4.com\/en\/wp-content\/uploads\/2021\/05\/RIMOWA-FLAGSHIP-HONG-KONG-G4GROUP-005.webp\" width=\"1200\" height=\"800\" alt=\"\" title=\"RIMOWA-FLAGSHIP-HONG KONG-G4GROUP-005\" aria-label=\"RIMOWA-FLAGSHIP-HONG KONG-G4GROUP-005\" class=\"img-responsive wp-image-15358\" srcset=\"https:\/\/www.groupg4.com\/en\/wp-content\/uploads\/2021\/05\/RIMOWA-FLAGSHIP-HONG-KONG-G4GROUP-005-200x133.webp 200w, https:\/\/www.groupg4.com\/en\/wp-content\/uploads\/2021\/05\/RIMOWA-FLAGSHIP-HONG-KONG-G4GROUP-005-400x267.webp 400w, https:\/\/www.groupg4.com\/en\/wp-content\/uploads\/2021\/05\/RIMOWA-FLAGSHIP-HONG-KONG-G4GROUP-005-600x400.webp 600w, https:\/\/www.groupg4.com\/en\/wp-content\/uploads\/2021\/05\/RIMOWA-FLAGSHIP-HONG-KONG-G4GROUP-005-800x533.webp 800w, https:\/\/www.groupg4.com\/en\/wp-content\/uploads\/2021\/05\/RIMOWA-FLAGSHIP-HONG-KONG-G4GROUP-005.webp 1200w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 1215px) 312px, (min-width: 1124px) 415px, (min-width: 1032px) 623px, (min-width: 940px) 1032px, \" \/><\/div><\/div><\/div><div style=\"padding:8px;\" class=\"fusion-grid-column fusion-gallery-column fusion-gallery-column-4 hover-type-none fusion-element-grid\"><div class=\"fusion-gallery-image\"><div style=\"background-image:url(https:\/\/www.groupg4.com\/en\/wp-content\/uploads\/2021\/05\/RIMOWA-FLAGSHIP-HONG-KONG-G4GROUP-006.webp);padding-top:calc((100% + 16px) * 0.8 - 8px);background-position:;\" class=\"fusion-masonry-element-container\"><img decoding=\"async\" src=\"https:\/\/www.groupg4.com\/en\/wp-content\/uploads\/2021\/05\/RIMOWA-FLAGSHIP-HONG-KONG-G4GROUP-006.webp\" width=\"1200\" height=\"800\" alt=\"\" title=\"RIMOWA-FLAGSHIP-HONG KONG-G4GROUP-006\" aria-label=\"RIMOWA-FLAGSHIP-HONG KONG-G4GROUP-006\" class=\"img-responsive wp-image-15359\" srcset=\"https:\/\/www.groupg4.com\/en\/wp-content\/uploads\/2021\/05\/RIMOWA-FLAGSHIP-HONG-KONG-G4GROUP-006-200x133.webp 200w, https:\/\/www.groupg4.com\/en\/wp-content\/uploads\/2021\/05\/RIMOWA-FLAGSHIP-HONG-KONG-G4GROUP-006-400x267.webp 400w, https:\/\/www.groupg4.com\/en\/wp-content\/uploads\/2021\/05\/RIMOWA-FLAGSHIP-HONG-KONG-G4GROUP-006-600x400.webp 600w, https:\/\/www.groupg4.com\/en\/wp-content\/uploads\/2021\/05\/RIMOWA-FLAGSHIP-HONG-KONG-G4GROUP-006-800x533.webp 800w, https:\/\/www.groupg4.com\/en\/wp-content\/uploads\/2021\/05\/RIMOWA-FLAGSHIP-HONG-KONG-G4GROUP-006.webp 1200w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 1215px) 312px, (min-width: 1124px) 415px, (min-width: 1032px) 623px, (min-width: 940px) 1032px, \" \/><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-title title fusion-title-1 fusion-title-center fusion-title-text fusion-title-size-four\" style=\"--awb-margin-top:40px;--awb-margin-top-small:20px;--awb-margin-right-small:0px;--awb-margin-bottom-small:15px;--awb-margin-left-small:0px;--awb-font-size:19px;\"><div class=\"title-sep-container title-sep-container-left\"><div class=\"title-sep sep- sep-solid\" style=\"border-color:#e0dede;\"><\/div><\/div><span class=\"awb-title-spacer\"><\/span><h4 class=\"fusion-title-heading title-heading-center fusion-responsive-typography-calculated\" style=\"font-family:&quot;Ubuntu&quot;;font-style:italic;font-weight:300;margin:0;font-size:1em;--fontSize:19;--minFontSize:19;line-height:1.23;\"><a href=\"https:\/\/www.groupg4.com\/en\/projects\/\"> + Return to projects portfolio<\/a><\/h4><span class=\"awb-title-spacer\"><\/span><div class=\"title-sep-container title-sep-container-right\"><div class=\"title-sep sep- sep-solid\" style=\"border-color:#e0dede;\"><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_1_6 1_6 fusion-flex-column fusion-flex-align-self-flex-start\" style=\"--awb-bg-size:cover;--awb-width-large:16.666666666667%;--awb-margin-top-large:20px;--awb-spacing-right-large:11.52%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:8.64%;--awb-width-medium:100%;--awb-order-medium:1;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:1;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-center fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\"><p style=\"text-align: center;\"><strong>\/ RIMOWA \/<\/strong><br \/>\nFlagship Hong Kong<\/p>\n<\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-top:20px;margin-bottom:20px;width:100%;\"><\/div><div class=\"fusion-text fusion-text-2\"><p>Typology: Retail<br \/>\nDate: 2019<br \/>\nSite: Canton Rd, Tsim Sha Tsui, Hong Kong, China<br \/>\nArea: 220 sqm<br \/>\nCollaborators:<br \/>\nClient: Rimowa<\/p>\n<\/div><div class=\"fusion-text fusion-text-3\" style=\"--awb-font-size:14px;\"><p>#design development, site supervision, project management<\/p>\n<\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":15355,"menu_order":41,"comment_status":"open","ping_status":"closed","template":"","format":"standard","meta":{"footnotes":""},"portfolio_category":[22],"portfolio_skills":[],"portfolio_tags":[],"class_list":["post-15354","avada_portfolio","type-avada_portfolio","status-publish","format-standard","has-post-thumbnail","hentry","portfolio_category-international-retail"],"_links":{"self":[{"href":"https:\/\/www.groupg4.com\/en\/wp-json\/wp\/v2\/avada_portfolio\/15354","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.groupg4.com\/en\/wp-json\/wp\/v2\/avada_portfolio"}],"about":[{"href":"https:\/\/www.groupg4.com\/en\/wp-json\/wp\/v2\/types\/avada_portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/www.groupg4.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.groupg4.com\/en\/wp-json\/wp\/v2\/comments?post=15354"}],"version-history":[{"count":0,"href":"https:\/\/www.groupg4.com\/en\/wp-json\/wp\/v2\/avada_portfolio\/15354\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.groupg4.com\/en\/wp-json\/wp\/v2\/media\/15355"}],"wp:attachment":[{"href":"https:\/\/www.groupg4.com\/en\/wp-json\/wp\/v2\/media?parent=15354"}],"wp:term":[{"taxonomy":"portfolio_category","embeddable":true,"href":"https:\/\/www.groupg4.com\/en\/wp-json\/wp\/v2\/portfolio_category?post=15354"},{"taxonomy":"portfolio_skills","embeddable":true,"href":"https:\/\/www.groupg4.com\/en\/wp-json\/wp\/v2\/portfolio_skills?post=15354"},{"taxonomy":"portfolio_tags","embeddable":true,"href":"https:\/\/www.groupg4.com\/en\/wp-json\/wp\/v2\/portfolio_tags?post=15354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}